{"id":25010,"date":"2019-03-28T16:14:55","date_gmt":"2019-03-28T15:14:55","guid":{"rendered":"http:\/\/www.vincenzopaglia.it\/?p=25010"},"modified":"2019-03-28T16:14:55","modified_gmt":"2019-03-28T15:14:55","slug":"nous-ne-ferons-pas-le-sale-boulot-de-la-mort","status":"publish","type":"post","link":"https:\/\/www.vincenzopaglia.it\/index.php\/nous-ne-ferons-pas-le-sale-boulot-de-la-mort.html","title":{"rendered":"Nous ne ferons pas le sale boulot de la mort"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Je suis particuli\u00e8rement reconnaissant pour l\u2019invitation qui m\u2019a \u00e9t\u00e9 adress\u00e9e afin de participer \u00e0 ce congr\u00e8s promu par l\u2019Universit\u00e9 catholique \u00ab&nbsp;Notre-Dame-du-Bon-Conseil&nbsp;\u00bb, consacr\u00e9 au th\u00e8me \u00ab&nbsp;Contre la culture du d\u00e9chet pour une culture de l\u2019amour. Les soins palliatifs pour la promotion d\u2019une culture de responsabilit\u00e9 sociale&nbsp;\u00bb. Ce th\u00e8me rappelle non seulement l\u2019importance des soins palliatifs comme mod\u00e8le clinique pour g\u00e9rer la maladie avanc\u00e9e jusqu\u2019au passage de la mort, mais aussi leur pertinence pour la promotion d\u2019une culture des soins dans une soci\u00e9t\u00e9 comme la n\u00f4tre, qui se laisse facilement surprendre par ce que le pape stigmatise comme \u00ab&nbsp;culture du d\u00e9chet&nbsp;\u00bb. Il est, en effet, fr\u00e9quent dans notre soci\u00e9t\u00e9 actuelle que les malades et leurs familles soient doublement victimes\u2009: d\u2019une part de la maladie et de l\u2019autre de l\u2019abandon.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les soins palliatifs luttent de fa\u00e7on d\u00e9cisive non seulement contre cette logique perverse, mais ils r\u00e9pondent au besoin radical qu\u2019ont les personnes, d\u2019\u00eatre toujours accompagn\u00e9es, surtout dans les moments les plus difficiles, comme peut l\u2019\u00eatre celui de la maladie dans le passage de la mort. \u00c0 plusieurs reprises, le Magist\u00e8re de l\u2019\u00c9glise catholique est intervenu r\u00e9cemment dans ce sens. Derni\u00e8rement, le pape Fran\u00e7ois a parl\u00e9 des soins palliatifs comme une \u00ab&nbsp;expression de l\u2019attitude proprement humaine \u00e0 prendre soin les uns des autres, en particulier de ceux qui souffrent. Ceux-ci t\u00e9moignent du fait que la personne humaine demeure toujours pr\u00e9cieuse, m\u00eame si elle est marqu\u00e9e par la vieillesse et par la maladie. La personne, en effet, en toutes circonstances,&nbsp;<a href=\"https:\/\/www.la-croix.com\/Urbi-et-Orbi\/Archives\/Documentation-catholique-n-2519-K\/Les-traitements-palliatifs-valorisent-la-personne-2015-03-19-1292977\">est un bien pour elle-m\u00eame et pour les autres, et elle est aim\u00e9e de Dieu<\/a>&nbsp;\u00bb&nbsp;<a href=\"https:\/\/www.la-croix.com\/Urbi-et-Orbi\/Documentation-catholique\/Saint-Siege\/Nous-ferons-pas-sale-boulot-mort-Tirana-Mgr-Paglia-promeut-culture-palliative-soins-2019-03-26-1201011518#note_1\">(1)<\/a>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">L\u2019urgence de promouvoir les \u00ab&nbsp;soins palliatifs&nbsp;\u00bb<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Par cons\u00e9quent, je crois qu\u2019il est urgent de promouvoir les \u00ab&nbsp;soins palliatifs&nbsp;\u00bb partout dans le monde. Notre rencontre d\u2019aujourd\u2019hui, qui a lieu au si\u00e8ge de la Facult\u00e9 de m\u00e9decine est en cela exemplaire. Tout d\u2019abord, car elle fait comprendre l\u2019importance d\u2019encourager les soins palliatifs dans leur aspect scientifique, culturel et didactique. Cela me semble \u00eatre, en effet, une belle co\u00efncidence que de parler de ce th\u00e8me, quelques jours seulement apr\u00e8s la premi\u00e8re pierre pos\u00e9e de l\u2019h\u00f4pital li\u00e9 \u00e0 cette universit\u00e9. Il est important que les soins palliatifs entrent \u00e0 faire partie des disciplines universitaires. Nous savons, de fait, que souvent le nombre d\u2019\u00e9tudiants, que ce soit en m\u00e9decine ou pour les formations d\u2019infirmiers d\u00e9sireux de se consacrer aux soins des malades en fin de vie et surtout des personnes \u00e2g\u00e9es, est faible. D\u00e9velopper la consid\u00e9ration pour les soins palliatifs signifie aussi faire red\u00e9couvrir la vocation la plus profonde de la m\u00e9decine qui consiste avant tout \u00e0 prendre soin.&nbsp;<a href=\"https:\/\/www.la-croix.com\/Urbi-et-Orbi\/Documentation-catholique\/Saint-Siege\/Le-cardinal-Parolin-encourage-lAcademie-vie-redecouvrir-vocation-medecine-prendre-soin-2018-04-27-1200934998\">Le cardinal Parolin au nom du pape Fran\u00e7ois le rappelait \u00e0 l\u2019Acad\u00e9mie de la vie<\/a>\u2009: \u00ab&nbsp;La t\u00e2che de la m\u00e9decine est de prendre toujours soin, m\u00eame si gu\u00e9rir n\u2019est pas toujours possible. Il est certain que l\u2019entreprise m\u00e9dicale est fond\u00e9e sur l\u2019inlassable effort d\u2019acqu\u00e9rir de nouvelles connaissances et de vaincre un nombre toujours plus grand de maladies. Or, les soins palliatifs introduisent, \u00e0 l\u2019int\u00e9rieur de la pratique clinique, la prise de conscience que la limite exige non seulement d\u2019\u00eatre repouss\u00e9e et combattue, mais aussi reconnue et accept\u00e9e. Et cela signifie ne pas abandonner les personnes malades, mais \u00eatre, au contraire, proches d\u2019elles, les accompagner dans l\u2019\u00e9preuve difficile qui se pr\u00e9sente \u00e0 la fin de leur vie. Lorsque toutes les ressources du \u201cfaire\u201d semblent \u00eatre \u00e9puis\u00e9es, c\u2019est alors que surgit l\u2019aspect le plus important dans les relations humaines qui est celui de l\u2019\u201c\u00eatre\u201d, \u00eatre pr\u00e9sent, \u00eatre proche, \u00eatre accueillant. Cela implique \u00e9galement de partager l\u2019impuissance de celui qui atteint le point extr\u00eame de sa vie. En faisant preuve de solidarit\u00e9 au moment o\u00f9 l\u2019action n\u2019arrive plus \u00e0 avoir un impact sur le cours des \u00e9v\u00e9nements, la limite peut en modifier le sens\u2009: elle devient non plus un lieu de s\u00e9paration et de solitude, mais une occasion de rencontre et de communion&nbsp;\u00bb&nbsp;<a href=\"https:\/\/www.la-croix.com\/Urbi-et-Orbi\/Documentation-catholique\/Saint-Siege\/Nous-ferons-pas-sale-boulot-mort-Tirana-Mgr-Paglia-promeut-culture-palliative-soins-2019-03-26-1201011518#note_2\">(2)<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ce sont des r\u00e9flexions particuli\u00e8rement importantes. C\u2019est dans cette perspective-l\u00e0 que l\u2019on comprend, davantage encore, combien promouvoir les soins palliatifs encourage la culture de l\u2019attention r\u00e9ciproque qui unit les droits et les devoirs\u2009: tout le monde a le droit d\u2019\u00eatre accompagn\u00e9 et soign\u00e9, et tout le monde a le devoir d\u2019accompagner et de soigner. J\u2019aime rappeler que le terme palliatif vient de<em>&nbsp;pallium&nbsp;<\/em>(un mot latin qui signifie manteau)\u2009: le plus faible a besoin d\u2019\u00eatre entour\u00e9 du manteau de l\u2019amour. Nous savons combien cette dimension est enracin\u00e9e dans la sensibilit\u00e9 \u00e9vang\u00e9lique. Mais elle est \u00e9galement pr\u00e9sente dans d\u2019autres traditions religieuses. Je pourrais citer, pour donner un seul exemple, une sourate du Coran d\u00e9couverte r\u00e9cemment\u2009: \u00ab&nbsp;Que la tendresse te recouvre, toi, l\u2019autre, comme un manteau&nbsp;\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le pape Fran\u00e7ois, dans cette dimension r\u00e9v\u00e9latrice, affirme\u2009: \u00ab&nbsp;Saisir dans sa propre exp\u00e9rience combien la vie humaine est re\u00e7ue des autres, qui nous ont mis au monde et se d\u00e9veloppe gr\u00e2ce \u00e0 leur soin, nous am\u00e8ne \u00e0 comprendre plus profond\u00e9ment le sens de la dimension passive qui la caract\u00e9rise. Il semble alors raisonnable de jeter un pont entre ces soins que l\u2019on a re\u00e7us depuis le d\u00e9but de la vie et qui ont permis \u00e0 celle-ci de se d\u00e9ployer pleinement et les soins \u00e0 offrir de mani\u00e8re responsable aux autres, au long des g\u00e9n\u00e9rations jusqu\u2019\u00e0 embrasser toute la famille humaine. C\u2019est sur ce chemin que peut s\u2019allumer l\u2019\u00e9tincelle qui relie l\u2019exp\u00e9rience du partage plein d\u2019amour de la vie humaine jusqu\u2019\u00e0 son myst\u00e9rieux d\u00e9part, avec l\u2019annonce \u00e9vang\u00e9lique qui voit tout le monde comme des enfants du m\u00eame P\u00e8re et qui reconna\u00eet en chacun son image inviolable. Ce lien pr\u00e9cieux d\u00e9fend une dignit\u00e9 humaine qui ne cesse de vivre, pas m\u00eame avec la perte de la sant\u00e9, du r\u00f4le social et du contr\u00f4le sur son propre corps. C\u2019est alors que les soins palliatifs montrent leur valeur, non seulement pour la pratique m\u00e9dicale \u2013 pour que, m\u00eame lorsqu\u2019ils agissent avec efficacit\u00e9 en r\u00e9alisant des gu\u00e9risons parfois spectaculaires, on n\u2019oublie pas cette attitude de fond qui est \u00e0 la racine de toute relation de soins \u2013 mais aussi plus g\u00e9n\u00e9ralement pour toute la coexistence humaine&nbsp;\u00bb&nbsp;<a href=\"https:\/\/www.la-croix.com\/Urbi-et-Orbi\/Documentation-catholique\/Saint-Siege\/Nous-ferons-pas-sale-boulot-mort-Tirana-Mgr-Paglia-promeut-culture-palliative-soins-2019-03-26-1201011518#note_3\">(3)<\/a>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Le projet \u00ab&nbsp;Pal-life&nbsp;\u00bb de l\u2019Acad\u00e9mie pontificale pour la vie<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019Acad\u00e9mie pontificale pour la vie s\u2019est engag\u00e9e afin que tout cela puisse advenir au niveau de l\u2019\u00c9glise catholique, partout dans le monde. Elle a fait siennes les paroles que le pape Fran\u00e7ois a prononc\u00e9es au cours de l\u2019Audience de la XXII<sup>e<\/sup>&nbsp;Assembl\u00e9e g\u00e9n\u00e9rale de l\u2019Acad\u00e9mie pontificale pour la vie, dans le contexte de laquelle \u00e9tait organis\u00e9 le Congr\u00e8s&nbsp;<em>Assisting the Elderly and Palliative Care<\/em>\u2009: \u00ab&nbsp;J\u2019appr\u00e9cie votre engagement scientifique et culturel pour garantir que les soins palliatifs rejoignent tous ceux qui en ont besoin. J\u2019encourage les professionnels et les \u00e9tudiants \u00e0 se sp\u00e9cialiser dans ce type d\u2019assistance qui ne poss\u00e8de pas moins de valeur sous pr\u00e9texte qu\u2019il \u201cne sauve pas la vie\u201d. Les soins palliatifs r\u00e9alisent quelque chose de tout aussi important\u2009: ils valorisent la personne. J\u2019exhorte tous ceux qui, \u00e0 divers titres, sont engag\u00e9s dans le domaine des soins palliatifs, \u00e0 pratiquer cet engagement en conservant int\u00e8gre l\u2019esprit de service et en se rappelant que toute connaissance m\u00e9dicale n\u2019est vraiment une science, dans son sens le plus noble, que si elle se situe comme une aide en vue du bien de l\u2019homme, un bien qui ne peut jamais \u00eatre atteint \u201ccontre\u201d sa vie et sa dignit\u00e9. C\u2019est cette capacit\u00e9 \u00e0 servir la vie et la dignit\u00e9 de la personne malade, y compris quand elle est \u00e2g\u00e9e, qui mesure le v\u00e9ritable progr\u00e8s de la m\u00e9decine et de la soci\u00e9t\u00e9 tout enti\u00e8re. Je redis l\u2019appel de saint Jean-Paul&nbsp;II\u2009: \u201cRespecte, d\u00e9fends, aime et sers la vie, toute vie humaine\u2009!&nbsp;<a href=\"https:\/\/www.la-croix.com\/Urbi-et-Orbi\/Archives\/Documentation-catholique-n-2519-K\/Les-traitements-palliatifs-valorisent-la-personne-2015-03-19-1292977\">C\u2019est seulement sur cette voie que tu trouveras la justice, le d\u00e9veloppement, la libert\u00e9 v\u00e9ritable, la paix et le bonheur\u2009!<\/a>\u201d&nbsp;\u00bb&nbsp;<a href=\"https:\/\/www.la-croix.com\/Urbi-et-Orbi\/Documentation-catholique\/Saint-Siege\/Nous-ferons-pas-sale-boulot-mort-Tirana-Mgr-Paglia-promeut-culture-palliative-soins-2019-03-26-1201011518#note_4\">(4)<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dans le souhait de donner suite aux paroles du Saint-P\u00e8re, l\u2019Acad\u00e9mie pontificale pour la vie a lanc\u00e9 le projet \u00ab&nbsp;Pal-Life&nbsp;\u00bb qui a pour vocation de promouvoir des initiatives en faveur du d\u00e9veloppement et de la diffusion des soins palliatifs dans le monde ainsi que d\u2019encourager la culture du soin et de l\u2019accompagnement jusqu\u2019\u00e0 la fin de vie des malades. Des \u00e9v\u00e9nements internationaux ont ainsi d\u00e9j\u00e0 \u00e9t\u00e9 organis\u00e9s, \u00e0 Houston, aux \u00c9tats-Unis, \u00e0 Doha, au Qatar, \u00e0 Rome et \u00e0 Milan. Au mois de mai 2019, une rencontre aura lieu au Br\u00e9sil pour la mise en \u0153uvre [du projet] en Am\u00e9rique du Sud, puis fin septembre au Rwanda pour affronter le th\u00e8me sur le continent africain. Il existe, en outre, un aspect qu\u2019il me para\u00eet opportun de souligner, celui des soins palliatifs dans le contexte \u0153cum\u00e9nique et interreligieux. Deux d\u00e9clarations communes ont d\u00e9j\u00e0 \u00e9t\u00e9 sign\u00e9es entre l\u2019Acad\u00e9mie pontificale pour la vie et l\u2019\u00c9glise m\u00e9thodiste am\u00e9ricaine ainsi qu\u2019avec la Qatar Foundation. Une nouvelle d\u00e9claration interreligieuse est en cours d\u2019\u00e9laboration avec les religions juive et islamique. Cet int\u00e9r\u00eat particulier pour la perspective interreligieuse d\u00e9rive du sentiment que l\u2019attention compl\u00e8te \u00e0 la personne, qui est \u00e0 la base des soins palliatifs, ne r\u00e9pond pas aux enjeux \u00e9conomiques qui gouvernent notre culture contemporaine et qui conduisent \u00e0 une \u00ab&nbsp;culture du gaspillage&nbsp;\u00bb. Une nouvelle alliance entre foi et humanisme nous permet d\u2019affirmer qu\u2019\u00e0 l\u2019int\u00e9rieur de la vie humaine, m\u00eame lorsqu\u2019elle est fragile et apparemment vaincue par la maladie, il est une pr\u00e9ciosit\u00e9 intangible. Les soins palliatifs incarnent une vision de l\u2019homme qui est profond\u00e9ment religieuse et en m\u00eame temps profond\u00e9ment humaine. \u00c0 mon avis, cette vision est la v\u00e9ritable \u00e2me et la v\u00e9ritable force des soins palliatifs.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dans cet horizon, je suis heureux de pr\u00e9senter dans ce lieu \u2013 il s\u2019agit de la premi\u00e8re pr\u00e9sentation publique apr\u00e8s l\u2019Assembl\u00e9e g\u00e9n\u00e9rale de f\u00e9vrier dernier \u2013 un \u00ab&nbsp;Livre blanc&nbsp;\u00bb qui sera envoy\u00e9 aux Universit\u00e9s et h\u00f4pitaux catholiques dans le monde entier pour favoriser la connaissance et la pratique des soins palliatifs. \u00c0 travers ce texte, nous voulons promouvoir une \u00ab&nbsp;culture palliative&nbsp;\u00bb, \u00e0 la fois pour r\u00e9pondre \u00e0 la tentation qui vient de l\u2019euthanasie et du suicide assist\u00e9, et surtout pour faire m\u00fbrir cette \u00ab&nbsp;culture du soin&nbsp;\u00bb qui permet d\u2019offrir une compagnie d\u2019amour jusqu\u2019au passage de la mort. De cette fa\u00e7on, on aide la m\u00e9decine elle-m\u00eame \u00e0 red\u00e9couvrir sa t\u00e2che qui est certainement celle de la \u00ab&nbsp;gu\u00e9rison&nbsp;\u00bb, qui joue, dans la m\u00e9decine contemporaine, un r\u00f4le pr\u00e9pond\u00e9rant, tout en \u00e9vitant d\u2019en faire l\u2019unique objectif \u00e0 atteindre \u00e0 tout prix. En effet, le risque serait d\u2019aller au-del\u00e0 du caract\u00e8re raisonnable dans l\u2019utilisation des traitements m\u00e9dicaux et d\u2019aboutir au soi-disant \u00ab&nbsp;acharnement th\u00e9rapeutique&nbsp;\u00bb qui procure au patient d\u2019inutiles souffrances. Bien entendu, l\u2019abandon th\u00e9rapeutique est toujours \u00e0 exclure quand la possibilit\u00e9 d\u2019obtenir la gu\u00e9rison dispara\u00eet. Il faut \u00eatre clair\u2009: si on ne peut pas gu\u00e9rir, on peut encore soulager la douleur et continuer \u00e0 prendre soin de cette personne. Le patient ingu\u00e9rissable n\u2019est jamais incurable. Il ne faut pas oublier la limite radicale qui fait partie de notre existence sur cette terre. L\u2019illusion de l\u2019immortalit\u00e9, qui sous-tend au seul objectif de la gu\u00e9rison, est tr\u00e8s dangereuse. La radicale finitude humaine conduit \u00e0 exclure avec force l\u2019obstination \u00e0 vouloir utiliser des traitements qui infligent des souffrances inutiles et quelquefois m\u00eames dangereuses au patient. Il ne faut toutefois jamais abandonner le malade, m\u00eame lorsque la gu\u00e9rison n\u2019est plus possible.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nous savons combien les soins palliatifs ont \u00e9t\u00e9 protagonistes de la r\u00e9cup\u00e9ration d\u2019un accompagnement complet du malade au sein de la m\u00e9decine contemporaine. Prendre soin du malade est un pas indispensable \u00e0 accomplir. Parfois, les sympt\u00f4mes d\u2019un malaise psychologique et d\u2019une souffrance existentielle li\u00e9s \u00e0 la maladie surgissent de mani\u00e8re improvis\u00e9e et d\u00e9vastatrice, m\u00eame pour un individualisme r\u00e9pandu qui laisse seuls ceux qui auraient le plus besoin de soutien et d\u2019accompagnement. Si la m\u00e9decine peut \u00ab&nbsp;\u00e9chouer&nbsp;\u00bb \u00e0 obtenir la gu\u00e9rison, elle n\u2019\u00e9choue jamais en prenant soin du malade. C\u2019est la raison pour laquelle, malgr\u00e9 les remarquables et constants progr\u00e8s scientifiques, le seul et peut-\u00eatre unique domaine o\u00f9 l\u2019on ait la certitude d\u2019atteindre toujours l\u2019objectif est dans celui de prendre soin de la personne malade.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">L\u2019urgence d\u2019une nouvelle fa\u00e7on d\u2019\u00eatre proche de celui qui est faible<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Il y a peu de culture de l\u2019accompagnement parce qu\u2019il y a aussi peu d\u2019amour gratuit. Dans un de mes r\u00e9cents volumes,&nbsp;<em>Sorella morte<\/em>(\u00ab&nbsp;Ma s\u0153ur la mort&nbsp;\u00bb), j\u2019ai soulign\u00e9 l\u2019urgence d\u2019une nouvelle fa\u00e7on d\u2019\u00eatre proche de celui qui est faible, en particulier de celui qui doit affronter l\u2019ultime \u00e9tape de sa vie, dans le passage de la mort. Et je crois que la pastorale chr\u00e9tienne est appel\u00e9e \u00e9galement \u00e0 s\u2019interroger s\u00e9rieusement sur les causes de la rar\u00e9faction de la pr\u00e9dication sur la mort et sur les r\u00e9alit\u00e9s ultimes. Faute, selon moi, \u00e0 un \u00ab&nbsp;affaiblissement de la pr\u00e9dication de l\u2019\u00c9vangile de la mort, de la r\u00e9surrection et de la vie \u00e9ternelle. Il est devenu toujours plus rare, h\u00e9las, d\u2019\u00e9couter la pr\u00e9dication sur les derniers \u00e9v\u00e9nements de la vie et sur le myst\u00e8re de la vie au-del\u00e0 de la mort&nbsp;\u00bb (p.&nbsp;217)&nbsp;<a href=\"https:\/\/www.la-croix.com\/Urbi-et-Orbi\/Documentation-catholique\/Saint-Siege\/Nous-ferons-pas-sale-boulot-mort-Tirana-Mgr-Paglia-promeut-culture-palliative-soins-2019-03-26-1201011518#note_5\">(5)<\/a>. Nos soci\u00e9t\u00e9s sont plus pauvres en paroles sur le myst\u00e8re du passage que la mort repr\u00e9sente dans l\u2019existence humaine. Par ailleurs, elles sont toujours plus sceptiques quant \u00e0 parler de la mort comme fin de vie. Ce n\u2019est pas le lieu ici pour m\u2019attarder sur cet aspect. Je veux seulement dire que je pr\u00e9f\u00e8re souligner la mort comme un passage, avec tout le bagage culturel et spirituel que cela comporte. Nous \u2013 chacun de nous, toutes les g\u00e9n\u00e9rations qui se suivent tout au long de l\u2019histoire \u2013 ne sommes pas une parenth\u00e8se entre deux rien. La mort n\u2019est pas la fin. Ce serait une profonde injustice\u2009! M\u00eame la raison ne peut le supporter\u2009: qu\u2019en serait-il de tout le bien que nous avons fait, des affections, des liens\u2009? R\u00e9fl\u00e9chir sur le th\u00e8me des soins palliatifs signifie aussi se demander quelles sont les paroles que nous devons r\u00e9apprendre pour accompagner celui qui vit les moments ultimes de son existence sur terre.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">R\u00e9p\u00e9ter n\u00e9anmoins que la personne humaine est toujours digne de respect et d\u2019attention, et que jamais elle ne doit \u00eatre mise de c\u00f4t\u00e9 ou rejet\u00e9e, et cela quelles que soient ses conditions, est une conviction qu\u2019il ne faut cesser de rappeler. Tout comme il convient de redire que \u00ab&nbsp;prendre soin&nbsp;\u00bb de l\u2019autre fait partie de la mission de toute personne humaine. C\u2019est une dimension qui exige un choix, mais c\u2019est pr\u00e9cis\u00e9ment ce choix-l\u00e0 qui distingue la dimension anthropologique du reste de la cr\u00e9ation. Or, c\u2019est dans cet horizon de service \u00e0 la vie et \u00e0 la dignit\u00e9 de la personne, surtout quand elle est malade et affaiblie, que se mesure la qualit\u00e9 de la personne mais aussi de la soci\u00e9t\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le mouvement des soins palliatifs, par cons\u00e9quent, en m\u00eame temps qu\u2019il exprime une fa\u00e7on savante d\u2019\u00eatre \u00e0 c\u00f4t\u00e9 de celui qui souffre, devient aussi un message de la mani\u00e8re dont concevoir l\u2019existence humaine. La communaut\u00e9 des soins palliatifs t\u00e9moigne d\u2019une nouvelle fa\u00e7on de coexister qui met au centre la personne et son bien-\u00eatre vers lequel non seulement l\u2019individu, mais la communaut\u00e9 tout enti\u00e8re tend. Dans cette communaut\u00e9, le bien de chacun est recherch\u00e9 comme \u00e9tant le bien pour tous. Les soins palliatifs repr\u00e9sentent un droit humain et nous voyons avec satisfaction que divers programmes internationaux s\u2019organisent pour mettre en \u0153uvre tout cela. Mais le vrai droit humain de toute personne est de continuer \u00e0 \u00eatre reconnue et accueillie comme membre de la soci\u00e9t\u00e9, comme partie d\u2019une communaut\u00e9. Avec la parabole du Samaritain, l\u2019\u00c9vangile demande l\u2019engagement personnel pour le soin de celui qui a besoin. Il faut remarquer que le Samaritain n\u2019est pas un croyant\u2009! l\u2019\u00c9glise ne fait donc rien d\u2019extraordinaire quand elle se montre attentive \u00e0 la dimension du soin de malade. Elle ne fait que ce qui lui a \u00e9t\u00e9 demand\u00e9 par l\u2019\u00c9vangile. Les soins \u2013 m\u00eame les soins palliatifs \u2013 repr\u00e9sentent un droit (le vrai droit\u2009!) des personnes malades et mourantes. Je suis convaincu que les soins palliatifs peuvent \u00eatre protagonistes dans la r\u00e9cup\u00e9ration d\u2019une culture de l\u2019accompagnement qui doit qualifier la qualit\u00e9 spirituelle et humaine de la soci\u00e9t\u00e9 contemporaine.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">\u00ab&nbsp;Nous ne ferons pas le sale boulot de la mort&nbsp;\u00bb<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">En arrivant \u00e0 la conclusion, je voudrais redire ma conviction, qu\u2019il faut alimenter de toutes les fa\u00e7ons la recherche des meilleurs parcours pour promouvoir la sant\u00e9, pour d\u00e9fendre la personne humaine ainsi que ses droits fondamentaux et inali\u00e9nables. Le travail humain de soin, qui fait face \u00e0 la vuln\u00e9rabilit\u00e9 mat\u00e9rielle et spirituelle de nous humains, sous quelques formes et professions que ce soit, vit d\u00e9j\u00e0 et toujours sur le fil du paradoxe anti-utilitariste. Or, c\u2019est ce paradoxe qui nous rend humains.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les hommes et les femmes dont nous nous sommes engag\u00e9s \u00e0 prendre soin, sont, depuis la nuit des temps, des cr\u00e9atures mortelles. Et nous ne les gu\u00e9rirons pas de cela. Pourtant, rien n\u2019est plus universellement valorisant et \u00e9mouvant que notre combat quotidien contre les signes douloureux de la fragilit\u00e9 qui annonce notre condition mortelle. Nous luttons fermement pour que ce ne soit pas l\u2019avilissement de la mort qui d\u00e9cide de la valeur de la vie. Luttons afin que ce ne soit pas la maladie qui d\u00e9cide de l\u2019utilit\u00e9 de notre vie, de la valeur d\u2019une personne, de la v\u00e9rit\u00e9 de nos affections. Nous acceptons notre condition mortelle. R\u00e9sistons \u00e0 l\u2019illusion d\u00e9lirante de pouvoir effacer le myst\u00e8re de cet extr\u00eame passage, avec ses douloureux signes contradictoires.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le travail du soin est notre engagement \u00e0 rendre humain cette acceptation, en l\u2019emp\u00eachant de devenir complicit\u00e9. En conclusion, nous nous refusons de faire le sale boulot de la mort\u2009: m\u00eame seulement symboliquement. L\u2019acte du soin acceptera \u2013 et aidera \u00e0 accepter \u2013 sa propre limite infranchissable\u2009: avec toute la d\u00e9licatesse de l\u2019amour, avec tout le respect pour la personne, avec toute la force du d\u00e9vouement dont nous serons capables. Aucun acte de soin ne voudra cependant porter le signe de cette complicit\u00e9 avec la mort, m\u00eame pas dans l\u2019apparence.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Voil\u00e0 l\u2019enjeu \u2013 tr\u00e8s difficile et tr\u00e8s humain \u2013 qui est face \u00e0 nous et que nous devons affronter ensemble. L\u2019accompagnement \u00e0 accueillir la n\u00e9cessit\u00e9 de vivre humainement m\u00eame la mort, sans perdre l\u2019amour qui lutte contre son avilissement, est l\u2019objectif de la \u00ab\u00a0proximit\u00e9 responsable\u00a0\u00bb \u00e0 laquelle nous tous, en tant qu\u2019\u00eatres humains, sommes appel\u00e9s. La communaut\u00e9 tout enti\u00e8re doit y participer. Nous ne resterons pas \u00e0 regarder la mort qui fait son travail, sans rien faire. Mais nous ne ferons pas le sale boulot de la mort, qui nous d\u00e9livre de l\u2019inconfort, comme si c\u2019\u00e9tait un acte d\u2019amour. L\u2019amour pour la vie, dans laquelle nous avons aim\u00e9 et nous nous sommes aim\u00e9s, n\u2019est plus seulement \u00e0 nous\u2009: il appartient \u00e0 tous ceux avec qui il a \u00e9t\u00e9 partag\u00e9. Ainsi, cela doit \u00eatre, jusqu\u2019\u00e0 la fin. Personne ne doit se sentir coupable du poids que sa condition mortelle impose \u00e0 la communaut\u00e9 de ses semblables. Nous sommes humains. Et, l\u2019id\u00e9e humaine du soin est en contradiction avec l\u2019id\u00e9e de la maladie comme exclusion de la communaut\u00e9 et faute impardonnable. Sans parler de l\u2019\u00c9vangile qui, naturellement, nous en lib\u00e8re m\u00eame th\u00e9ologiquement.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.la-croix.com\/Urbi-et-Orbi\/Documentation-catholique\/Saint-Siege\/Nous-ferons-pas-sale-boulot-mort-Tirana-Mgr-Paglia-promeut-culture-palliative-soins-2019-03-26-1201011518\"> <\/a><em><a href=\"https:\/\/www.la-croix.com\/Urbi-et-Orbi\/Documentation-catholique\/Saint-Siege\/Nous-ferons-pas-sale-boulot-mort-Tirana-Mgr-Paglia-promeut-culture-palliative-soins-2019-03-26-1201011518\">Traduit de l\u2019italien par <\/a><strong><a href=\"https:\/\/www.la-croix.com\/Urbi-et-Orbi\/Documentation-catholique\/Saint-Siege\/Nous-ferons-pas-sale-boulot-mort-Tirana-Mgr-Paglia-promeut-culture-palliative-soins-2019-03-26-1201011518\">Sophie Lafon d\u2019Alessandro pour\u00a0La DC<\/a><\/strong><a href=\"https:\/\/www.la-croix.com\/Urbi-et-Orbi\/Documentation-catholique\/Saint-Siege\/Nous-ferons-pas-sale-boulot-mort-Tirana-Mgr-Paglia-promeut-culture-palliative-soins-2019-03-26-1201011518\">. <\/a><\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"http:\/\/www.vincenzopaglia.it\/index.php\/le-cure-palliative-per-la-promozione-di-una-cultura-di-responsabilita-sociale-2.html\"><strong>VERSIONE ORIGINALE<\/strong><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Je suis particuli\u00e8rement reconnaissant pour l\u2019invitation qui m\u2019a \u00e9t\u00e9 adress\u00e9e afin de participer \u00e0 ce congr\u00e8s promu par l\u2019Universit\u00e9 catholique \u00ab&nbsp;Notre-Dame-du-Bon-Conseil&nbsp;\u00bb, consacr\u00e9 au th\u00e8me \u00ab&nbsp;Contre la culture du d\u00e9chet pour une culture de l\u2019amour. Les soins palliatifs pour la promotion d\u2019une culture de responsabilit\u00e9 sociale&nbsp;\u00bb. Ce th\u00e8me rappelle non seulement l\u2019importance des soins palliatifs comme [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":24947,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14,3],"tags":[],"class_list":["post-25010","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-francais","category-interventi"],"jetpack_featured_media_url":"https:\/\/www.vincenzopaglia.it\/wp-content\/uploads\/2019\/03\/D18tfKGXcAArJM_-1.jpg","_links":{"self":[{"href":"https:\/\/www.vincenzopaglia.it\/index.php\/wp-json\/wp\/v2\/posts\/25010","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vincenzopaglia.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vincenzopaglia.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vincenzopaglia.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vincenzopaglia.it\/index.php\/wp-json\/wp\/v2\/comments?post=25010"}],"version-history":[{"count":1,"href":"https:\/\/www.vincenzopaglia.it\/index.php\/wp-json\/wp\/v2\/posts\/25010\/revisions"}],"predecessor-version":[{"id":25011,"href":"https:\/\/www.vincenzopaglia.it\/index.php\/wp-json\/wp\/v2\/posts\/25010\/revisions\/25011"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vincenzopaglia.it\/index.php\/wp-json\/wp\/v2\/media\/24947"}],"wp:attachment":[{"href":"https:\/\/www.vincenzopaglia.it\/index.php\/wp-json\/wp\/v2\/media?parent=25010"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vincenzopaglia.it\/index.php\/wp-json\/wp\/v2\/categories?post=25010"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vincenzopaglia.it\/index.php\/wp-json\/wp\/v2\/tags?post=25010"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}